{"id":346,"date":"2021-01-27T12:16:27","date_gmt":"2021-01-27T11:16:27","guid":{"rendered":"http:\/\/www.sainte-trinite.fr\/blog\/?p=346"},"modified":"2021-01-27T12:18:03","modified_gmt":"2021-01-27T11:18:03","slug":"maison-de-location-vacances-destrinitaires","status":"publish","type":"post","link":"http:\/\/www.sainte-trinite.fr\/blog\/maison-de-location-vacances-destrinitaires\/","title":{"rendered":"Maison de location vacances desTrinitaires"},"content":{"rendered":"<p>Vous recherchez une location \u00e0 la montagne en toute saison&#8230;?<\/p>\n<p>Nos soeurs trinitaires vous propose leur Maison \u00ab\u00a0Alpes-Montjoie\u00a0\u00bb \u00e0 Faucon de Barcelonnette.<\/p>\n<p>Trouvez <a href=\"https:\/\/institutionsaintetrinite-my.sharepoint.com\/:v:\/g\/personal\/marques_sainte-trinite_fr\/EbYfJ2sMWzJCr_tZQ2GEHJQBp06urIdF0i_-NSuKYZ__Fw?e=dkZ1uX\"><strong>ICI<\/strong><\/a> toutes les informations. N&rsquo;h\u00e9sitez pas.<\/p>\n<p>&nbsp;<\/p>\n<p>EM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous recherchez une location \u00e0 la montagne en toute saison&#8230;? Nos soeurs trinitaires vous propose leur Maison \u00ab\u00a0Alpes-Montjoie\u00a0\u00bb \u00e0 Faucon de Barcelonnette. Trouvez ICI toutes les informations. N&rsquo;h\u00e9sitez pas. &nbsp; EM<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,23,40],"tags":[],"_links":{"self":[{"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/posts\/346"}],"collection":[{"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/comments?post=346"}],"version-history":[{"count":1,"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/posts\/346\/revisions"}],"predecessor-version":[{"id":347,"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/posts\/346\/revisions\/347"}],"wp:attachment":[{"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/media?parent=346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/categories?post=346"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sainte-trinite.fr\/blog\/wp-json\/wp\/v2\/tags?post=346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}